{"id":2389,"date":"2022-06-08T23:30:31","date_gmt":"2022-06-08T21:30:31","guid":{"rendered":"https:\/\/www.busclassic.org\/?p=2389"},"modified":"2025-06-18T19:55:42","modified_gmt":"2025-06-18T17:55:42","slug":"ford-aa-caba","status":"publish","type":"post","link":"https:\/\/www.busclassic.org\/pt\/veiculos\/ford-aa-caba\/","title":{"rendered":"05. Ford AA &#8211; Caba (1929)"},"content":{"rendered":"<h2 class=\"wp-block-heading\">Dados de refer\u00eancia<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Chassi<\/strong>: Ford AA<\/li>\n\n\n\n<li><strong>Motor<\/strong>: Ford AA de 3258 cc e 40 CV<\/li>\n\n\n\n<li><strong>Carro\u00e7aria<\/strong>: Caba<\/li>\n\n\n\n<li><strong>Entrada em servi\u00e7o<\/strong>: 1929<\/li>\n\n\n\n<li><strong>Decalque<\/strong>: n\u00e3o o tem<\/li>\n\n\n\n<li><strong>Lugares<\/strong>: 17<\/li>\n\n\n\n<li><strong>Matr\u00edcula<\/strong>: B-36989<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Resenha hist\u00f3rica<\/h2>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><strong>El Ford AA: la versi\u00f3 industrial del Ford A<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p>El <strong>Ford AA<\/strong> era la versi\u00f3 per a <strong>cami\u00f3 o autob\u00fas<\/strong> del popular <strong>Ford A<\/strong>, amb una <strong>major dist\u00e0ncia entre eixos<\/strong> per permetre <strong>carrosseries de m\u00e9s volum<\/strong>.<\/p>\n\n\n\n<p>Es va produir a <strong>Detroit<\/strong> entre <strong>1928 i 1931<\/strong>. Com gaireb\u00e9 tots els <strong>xassissos de l\u2019\u00e8poca<\/strong>, es podia <strong>carrossar tant com a cami\u00f3 com a autob\u00fas o autocar<\/strong>. A m\u00e9s, es va fabricar <strong>sota llic\u00e8ncia<\/strong> en diversos pa\u00efsos com <strong>Espanya, Su\u00e8cia, Fran\u00e7a, Dinamarca<\/strong> i la <strong>Uni\u00f3 Sovi\u00e8tica<\/strong> (on fou la base del <strong>cami\u00f3 GAZ<\/strong>, utilitzat fins ben passada la <strong>Segona Guerra Mundial<\/strong>).<\/p>\n\n\n\n<p>La <strong>carrosseria<\/strong> \u00e9s la cl\u00e0ssica <strong>tancada<\/strong> de l\u2019\u00e8poca, amb <strong>estructura de fusta de freixe emplanxada<\/strong>, <strong>banquetes transversals corregudes<\/strong>, <strong>poc espai interior<\/strong> i una <strong>baca per a equipatges<\/strong> al sostre. Va ser constru\u00efda pel taller sabadellenc <strong>Carrosseries Caba<\/strong>, i es distingeix pel <strong>peculiar frontal amb escairats a 45\u00ba<\/strong>, caracter\u00edstic de bona part dels seus productes d\u2019aquell temps.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Fotografias<\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.busclassic.org\/wp-content\/uploads\/2018\/04\/POC_5583-1024x683.jpg\" alt=\"v\" class=\"wp-image-1108\" srcset=\"https:\/\/www.busclassic.org\/wp-content\/uploads\/2018\/04\/POC_5583-1024x683.jpg 1024w, https:\/\/www.busclassic.org\/wp-content\/uploads\/2018\/04\/POC_5583-300x200.jpg 300w, https:\/\/www.busclassic.org\/wp-content\/uploads\/2018\/04\/POC_5583-768x512.jpg 768w, https:\/\/www.busclassic.org\/wp-content\/uploads\/2018\/04\/POC_5583-830x554.jpg 830w, https:\/\/www.busclassic.org\/wp-content\/uploads\/2018\/04\/POC_5583-230x153.jpg 230w, https:\/\/www.busclassic.org\/wp-content\/uploads\/2018\/04\/POC_5583-350x234.jpg 350w, https:\/\/www.busclassic.org\/wp-content\/uploads\/2018\/04\/POC_5583-480x320.jpg 480w, https:\/\/www.busclassic.org\/wp-content\/uploads\/2018\/04\/POC_5583-272x182.jpg 272w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Ford AA \/ Caba<\/figcaption><\/figure>","protected":false},"excerpt":{"rendered":"<p>Coneix el Ford AA \u2013 Caba de 1929, un autob\u00fas hist\u00f2ric de 17 places amb motor de 40\u202fCV i carrosseria sabadellenca. Un cl\u00e0ssic del transport amb disseny robust i funcional.<\/p>","protected":false},"author":2,"featured_media":1108,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[41],"tags":[68,55,47],"class_list":["post-2389","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vehicles","tag-caba","tag-ford","tag-sagales"],"mb":[],"mfb_rest_fields":["title"],"_links":{"self":[{"href":"https:\/\/www.busclassic.org\/pt\/wp-json\/wp\/v2\/posts\/2389","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.busclassic.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.busclassic.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.busclassic.org\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.busclassic.org\/pt\/wp-json\/wp\/v2\/comments?post=2389"}],"version-history":[{"count":22,"href":"https:\/\/www.busclassic.org\/pt\/wp-json\/wp\/v2\/posts\/2389\/revisions"}],"predecessor-version":[{"id":5420,"href":"https:\/\/www.busclassic.org\/pt\/wp-json\/wp\/v2\/posts\/2389\/revisions\/5420"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.busclassic.org\/pt\/wp-json\/wp\/v2\/media\/1108"}],"wp:attachment":[{"href":"https:\/\/www.busclassic.org\/pt\/wp-json\/wp\/v2\/media?parent=2389"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.busclassic.org\/pt\/wp-json\/wp\/v2\/categories?post=2389"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.busclassic.org\/pt\/wp-json\/wp\/v2\/tags?post=2389"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}