{"id":5205,"date":"2025-06-17T20:32:18","date_gmt":"2025-06-17T18:32:18","guid":{"rendered":"https:\/\/www.busclassic.org\/?p=5205"},"modified":"2025-06-18T19:55:51","modified_gmt":"2025-06-18T17:55:51","slug":"renault-tn4b","status":"publish","type":"post","link":"https:\/\/www.busclassic.org\/pt\/veiculos\/renault-tn4b\/","title":{"rendered":"06. Renault TN4B (1931)"},"content":{"rendered":"<h2 class=\"wp-block-heading\">Dados de refer\u00eancia<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Chassi<\/strong>: Renault TN4B<\/li>\n\n\n\n<li><strong>Motor<\/strong>: Renault TN4B de 5883 cc e 58 CV<\/li>\n\n\n\n<li><strong>Carro\u00e7aria<\/strong>: STCRP (oficinas pr\u00f3prias dos autocarros de Paris)<\/li>\n\n\n\n<li><strong>Entrada em servi\u00e7o<\/strong>1931 (reformado de TN4A para TN4B em 1931)<\/li>\n\n\n\n<li><strong>Decalque<\/strong>: n\u00e3o o tem<\/li>\n\n\n\n<li><strong>Lugares<\/strong>: 32<\/li>\n\n\n\n<li><strong>Matr\u00edcula<\/strong>: H-8795-BBF<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Resenha hist\u00f3rica<\/h2>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><strong>Renault TN4A2: un cl\u00e0ssic del transport urb\u00e0 parisenc<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p>A petici\u00f3 de l\u2019<strong>empresa de transports urbans d\u2019autobusos de Par\u00eds<\/strong>, <strong>Renault<\/strong> va produir, l\u2019any <strong>1931<\/strong>, un total de <strong>320 unitats<\/strong> del nou model <strong>TN4A2<\/strong>, una evoluci\u00f3 del model <strong>PN<\/strong> amb un <strong>nou motor<\/strong> i una <strong>nova calandra<\/strong>.<\/p>\n\n\n\n<p>Els vehicles van ser <strong>carrossats als tallers de Championnet<\/strong> amb una <strong>nova carrosseria de quatre vidres<\/strong>, <strong>cabina sense vestibular<\/strong> i pensats per a <strong>agent doble<\/strong> (\u00e9s a dir, <strong>conductor + cobrador<\/strong>). La seva <strong>velocitat m\u00e0xima<\/strong> era de <strong>40 km\/h<\/strong>.<\/p>\n\n\n\n<p>Tot i aix\u00f2, el nou model present\u00e0 <strong>problemes mec\u00e0nics<\/strong>, especialment amb els <strong>blocs i les culates dels motors<\/strong>. Per aquest motiu, entre <strong>1936 i 1938<\/strong>, <strong>totes les unitats<\/strong> van ser <strong>reenginyades<\/strong> amb motors similars als del model <strong>TN4F<\/strong>, donant lloc al <strong>TN4B<\/strong>. Aquesta modificaci\u00f3 tamb\u00e9 implic\u00e0 el <strong>canvi de la calandra en V per una calandra plana<\/strong>.<\/p>\n\n\n\n<p>Entre <strong>1947 i 1949<\/strong>, es van <strong>vestibular les cabines<\/strong>, adaptant-les a les necessitats modernes del servei.<\/p>\n\n\n\n<p>Aquest vehicle prest\u00e0 <strong>servei a Par\u00eds fins al 1959<\/strong>, passant despr\u00e9s per diverses mans, fins que fou <strong>acreditat per Empresa Sagal\u00e9s<\/strong> a la regi\u00f3 de l\u2019<strong>Alv\u00e8rnia francesa<\/strong> per formar part de la seva <strong>col\u00b7lecci\u00f3 de vehicles hist\u00f2rics<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Fotografias<\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"684\" src=\"https:\/\/www.busclassic.org\/wp-content\/uploads\/2025\/06\/10-ralli-internacional-dautobusos-clssics_48087978473_o-1024x684.jpg\" alt=\"\" class=\"wp-image-5206\" srcset=\"https:\/\/www.busclassic.org\/wp-content\/uploads\/2025\/06\/10-ralli-internacional-dautobusos-clssics_48087978473_o-1024x684.jpg 1024w, https:\/\/www.busclassic.org\/wp-content\/uploads\/2025\/06\/10-ralli-internacional-dautobusos-clssics_48087978473_o-300x200.jpg 300w, https:\/\/www.busclassic.org\/wp-content\/uploads\/2025\/06\/10-ralli-internacional-dautobusos-clssics_48087978473_o-768x513.jpg 768w, https:\/\/www.busclassic.org\/wp-content\/uploads\/2025\/06\/10-ralli-internacional-dautobusos-clssics_48087978473_o-18x12.jpg 18w, https:\/\/www.busclassic.org\/wp-content\/uploads\/2025\/06\/10-ralli-internacional-dautobusos-clssics_48087978473_o-1000x668.jpg 1000w, https:\/\/www.busclassic.org\/wp-content\/uploads\/2025\/06\/10-ralli-internacional-dautobusos-clssics_48087978473_o-230x154.jpg 230w, https:\/\/www.busclassic.org\/wp-content\/uploads\/2025\/06\/10-ralli-internacional-dautobusos-clssics_48087978473_o-350x234.jpg 350w, https:\/\/www.busclassic.org\/wp-content\/uploads\/2025\/06\/10-ralli-internacional-dautobusos-clssics_48087978473_o-480x320.jpg 480w, https:\/\/www.busclassic.org\/wp-content\/uploads\/2025\/06\/10-ralli-internacional-dautobusos-clssics_48087978473_o-272x182.jpg 272w, https:\/\/www.busclassic.org\/wp-content\/uploads\/2025\/06\/10-ralli-internacional-dautobusos-clssics_48087978473_o.jpg 1384w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>","protected":false},"excerpt":{"rendered":"<p>Explora el Renault TN4B de 1931, un autob\u00fas parisenc hist\u00f2ric de 32 places amb motor de 58\u202fCV. Una pe\u00e7a \u00fanica que va circular fins al 1959 i forma part de la col\u00b7lecci\u00f3 de Sagal\u00e9s.<\/p>","protected":false},"author":1,"featured_media":5206,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[41],"tags":[459,75,52,47],"class_list":["post-5205","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vehicles","tag-franca","tag-paris","tag-renault","tag-sagales"],"mb":[],"mfb_rest_fields":["title"],"_links":{"self":[{"href":"https:\/\/www.busclassic.org\/pt\/wp-json\/wp\/v2\/posts\/5205","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.busclassic.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.busclassic.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.busclassic.org\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.busclassic.org\/pt\/wp-json\/wp\/v2\/comments?post=5205"}],"version-history":[{"count":9,"href":"https:\/\/www.busclassic.org\/pt\/wp-json\/wp\/v2\/posts\/5205\/revisions"}],"predecessor-version":[{"id":5421,"href":"https:\/\/www.busclassic.org\/pt\/wp-json\/wp\/v2\/posts\/5205\/revisions\/5421"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.busclassic.org\/pt\/wp-json\/wp\/v2\/media\/5206"}],"wp:attachment":[{"href":"https:\/\/www.busclassic.org\/pt\/wp-json\/wp\/v2\/media?parent=5205"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.busclassic.org\/pt\/wp-json\/wp\/v2\/categories?post=5205"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.busclassic.org\/pt\/wp-json\/wp\/v2\/tags?post=5205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}